{"id":3244,"date":"2014-03-19T15:50:17","date_gmt":"2014-03-19T19:50:17","guid":{"rendered":"https:\/\/www.seigneuriedutriton.com\/?page_id=3244"},"modified":"2014-09-11T15:50:25","modified_gmt":"2014-09-11T19:50:25","slug":"2012-en","status":"publish","type":"page","link":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/","title":{"rendered":"2012"},"content":{"rendered":"<h2>4 lbs and over<\/h2>\n<p><strong>\n<table id=\"wp-table-reloaded-id-45-no-1\" class=\"wp-table-reloaded wp-table-reloaded-id-45\">\n<thead>\n\t<tr class=\"row-1 odd\">\n\t\t<th class=\"column-1\">\u00a0\u00a0NAME<\/th><th class=\"column-2\">WEIGHT<\/th><th class=\"column-3\">LAKE<\/th><th class=\"column-4\">DATE<\/th>\n\t<\/tr>\n<\/thead>\n<tbody>\n\t<tr class=\"row-2 even\">\n\t\t<td class=\"column-1\">Julie Par\u00e9<\/td><td class=\"column-2\">4 lb<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n<\/tbody>\n<\/table>\n<\/strong><\/p>\n<h2>3 lbs and over<\/h2>\n<p><strong>\n<table id=\"wp-table-reloaded-id-44-no-1\" class=\"wp-table-reloaded wp-table-reloaded-id-44\">\n<thead>\n\t<tr class=\"row-1 odd\">\n\t\t<th class=\"column-1\">NAME<\/th><th class=\"column-2\">WEIGHT<\/th><th class=\"column-3\">LAKE<\/th><th class=\"column-4\">DATE<\/th>\n\t<\/tr>\n<\/thead>\n<tbody>\n\t<tr class=\"row-2 even\">\n\t\t<td class=\"column-1\"><\/td><td class=\"column-2\"><\/td><td class=\"column-3\"><\/td><td class=\"column-4\"><\/td>\n\t<\/tr>\n\t<tr class=\"row-3 odd\">\n\t\t<td class=\"column-1\">Alain Gigu\u00e8re<\/td><td class=\"column-2\">3 lb 1 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 20<\/td>\n\t<\/tr>\n\t<tr class=\"row-4 even\">\n\t\t<td class=\"column-1\">Andr\u00e9 Fortin<\/td><td class=\"column-2\">3 lb 2 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-5 odd\">\n\t\t<td class=\"column-1\">Anthony Beaul\u00e9<\/td><td class=\"column-2\">3 lb 7 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-6 even\">\n\t\t<td class=\"column-1\">Antoine Laroche<\/td><td class=\"column-2\">3 lb 5 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-7 odd\">\n\t\t<td class=\"column-1\">Christian Gagn\u00e9<\/td><td class=\"column-2\">3 lb 9 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-8 even\">\n\t\t<td class=\"column-1\">Claudie Bouillon<\/td><td class=\"column-2\">3 lb 6 oz<\/td><td class=\"column-3\">Foi<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-9 odd\">\n\t\t<td class=\"column-1\">Daniel Picard<\/td><td class=\"column-2\">3 lb <\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-10 even\">\n\t\t<td class=\"column-1\">David Lesage<\/td><td class=\"column-2\">3 lb 3 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">june 4<\/td>\n\t<\/tr>\n\t<tr class=\"row-11 odd\">\n\t\t<td class=\"column-1\">Eric Lamothe<\/td><td class=\"column-2\">3 lb 6 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-12 even\">\n\t\t<td class=\"column-1\">Gilles Blais<\/td><td class=\"column-2\">3 lb<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 22<\/td>\n\t<\/tr>\n\t<tr class=\"row-13 odd\">\n\t\t<td class=\"column-1\">Jacques Gaudreault<\/td><td class=\"column-2\">3 lb 3 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 9<\/td>\n\t<\/tr>\n\t<tr class=\"row-14 even\">\n\t\t<td class=\"column-1\">Jean Jacq<\/td><td class=\"column-2\">3 lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-15 odd\">\n\t\t<td class=\"column-1\">Jean Masson<\/td><td class=\"column-2\">3 lb<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-16 even\">\n\t\t<td class=\"column-1\">Jonathan Feignol<\/td><td class=\"column-2\">3 lb 2 oz<\/td><td class=\"column-3\">Foi<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-17 odd\">\n\t\t<td class=\"column-1\">Linda Smith<\/td><td class=\"column-2\">3 lb<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-18 even\">\n\t\t<td class=\"column-1\">Louise Vachon<\/td><td class=\"column-2\">3 lb 4 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 15<\/td>\n\t<\/tr>\n\t<tr class=\"row-19 odd\">\n\t\t<td class=\"column-1\">Marjolaine Gravel<\/td><td class=\"column-2\">3 lb 9 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-20 even\">\n\t\t<td class=\"column-1\">Richard Moreau<\/td><td class=\"column-2\">3 lb 5 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 25<\/td>\n\t<\/tr>\n\t<tr class=\"row-21 odd\">\n\t\t<td class=\"column-1\">Richard Moreau<\/td><td class=\"column-2\">3 lb 5 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 25<\/td>\n\t<\/tr>\n\t<tr class=\"row-22 even\">\n\t\t<td class=\"column-1\">Serge Boily<\/td><td class=\"column-2\">3 lb<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-23 odd\">\n\t\t<td class=\"column-1\">Serge Fortin<\/td><td class=\"column-2\">3 lb<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-24 even\">\n\t\t<td class=\"column-1\">St\u00e9phane Beaul\u00e9<\/td><td class=\"column-2\">3 lb 1 oz<\/td><td class=\"column-3\">Charit\u00e9 2<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-25 odd\">\n\t\t<td class=\"column-1\">\u00a0Nathalie Gauthier\u00a0<\/td><td class=\"column-2\">3 lb 2 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 13<\/td>\n\t<\/tr>\n\t<tr class=\"row-26 even\">\n\t\t<td class=\"column-1\">Eric Patrie<\/td><td class=\"column-2\">3 lb 1 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-27 odd\">\n\t\t<td class=\"column-1\">Etienne Vall\u00e9e<\/td><td class=\"column-2\">3 lb 2 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-28 even\">\n\t\t<td class=\"column-1\">Etienne Vall\u00e9e<\/td><td class=\"column-2\">3 lb 5 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance <\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-29 odd\">\n\t\t<td class=\"column-1\">Etienne Vall\u00e9e <\/td><td class=\"column-2\">3 lb<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n<\/tbody>\n<\/table>\n<\/strong><\/p>\n<h2>2 lbs and over<\/h2>\n<p><strong>\n<table id=\"wp-table-reloaded-id-43-no-1\" class=\"wp-table-reloaded wp-table-reloaded-id-43\">\n<thead>\n\t<tr class=\"row-1 odd\">\n\t\t<th class=\"column-1\">NAME<\/th><th class=\"column-2\">WEIGHT<\/th><th class=\"column-3\">LAKE<\/th><th class=\"column-4\">DATE<\/th>\n\t<\/tr>\n<\/thead>\n<tbody>\n\t<tr class=\"row-2 even\">\n\t\t<td class=\"column-1\">Francine Bilodeau<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Esp\u00e9rance <\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-3 odd\">\n\t\t<td class=\"column-1\">Sylvie Roy<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Foi<\/td><td class=\"column-4\">may 23<\/td>\n\t<\/tr>\n\t<tr class=\"row-4 even\">\n\t\t<td class=\"column-1\">Pierre Tremblay<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 13<\/td>\n\t<\/tr>\n\t<tr class=\"row-5 odd\">\n\t\t<td class=\"column-1\">Pierre L\u00e9veille<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-6 even\">\n\t\t<td class=\"column-1\">Marcel Roberts<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 26<\/td>\n\t<\/tr>\n\t<tr class=\"row-7 odd\">\n\t\t<td class=\"column-1\">Carl Verrier<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-8 even\">\n\t\t<td class=\"column-1\">St\u00e9phane Forget<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 3<\/td>\n\t<\/tr>\n\t<tr class=\"row-9 odd\">\n\t\t<td class=\"column-1\">Bruno Laroche<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-10 even\">\n\t\t<td class=\"column-1\">Caleb Gaumond<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">21 august<\/td>\n\t<\/tr>\n\t<tr class=\"row-11 odd\">\n\t\t<td class=\"column-1\">Bernard Lemelin<\/td><td class=\"column-2\">2 lb<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">june 13<\/td>\n\t<\/tr>\n\t<tr class=\"row-12 even\">\n\t\t<td class=\"column-1\">Gilles L\u00e9onard<\/td><td class=\"column-2\">2 lb 1 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">19 august<\/td>\n\t<\/tr>\n\t<tr class=\"row-13 odd\">\n\t\t<td class=\"column-1\">Frederic Vigneault<\/td><td class=\"column-2\">2 lb 1 oz<\/td><td class=\"column-3\">Charit\u00e9 <\/td><td class=\"column-4\">may 18<\/td>\n\t<\/tr>\n\t<tr class=\"row-14 even\">\n\t\t<td class=\"column-1\">C\u00e9drick Fortin<\/td><td class=\"column-2\">2 lb 1 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-15 odd\">\n\t\t<td class=\"column-1\">Pierre C\u00f4t\u00e9<\/td><td class=\"column-2\">2 lb 1 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">june 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-16 even\">\n\t\t<td class=\"column-1\">Alain Fiola<\/td><td class=\"column-2\">2 lb 1 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 9<\/td>\n\t<\/tr>\n\t<tr class=\"row-17 odd\">\n\t\t<td class=\"column-1\">Thomas Hudon<\/td><td class=\"column-2\">2 lb 1 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-18 even\">\n\t\t<td class=\"column-1\">Pierre Paul Imbeau<\/td><td class=\"column-2\">2 lb 1 oz<\/td><td class=\"column-3\">Foy<\/td><td class=\"column-4\">may 16<\/td>\n\t<\/tr>\n\t<tr class=\"row-19 odd\">\n\t\t<td class=\"column-1\">Luc Morissette<\/td><td class=\"column-2\">2 lb 2 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">14 may<\/td>\n\t<\/tr>\n\t<tr class=\"row-20 even\">\n\t\t<td class=\"column-1\">Fran\u00e7ois Fr\u00e9d\u00e9rick<\/td><td class=\"column-2\">2 lb 2 oz<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 23<\/td>\n\t<\/tr>\n\t<tr class=\"row-21 odd\">\n\t\t<td class=\"column-1\">Linda Tremblay<\/td><td class=\"column-2\">2 lb 2 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 31<\/td>\n\t<\/tr>\n\t<tr class=\"row-22 even\">\n\t\t<td class=\"column-1\">Pierre Lirette<\/td><td class=\"column-2\">2 lb 3 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-23 odd\">\n\t\t<td class=\"column-1\">Martin Cot\u00e9<\/td><td class=\"column-2\">2 lb 3 oz<\/td><td class=\"column-3\">Charit\u00e9 2<\/td><td class=\"column-4\">may 13<\/td>\n\t<\/tr>\n\t<tr class=\"row-24 even\">\n\t\t<td class=\"column-1\">\u00a0Louise Desrosiers<\/td><td class=\"column-2\">2 lb 3 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-25 odd\">\n\t\t<td class=\"column-1\">Louise Desrosiers<\/td><td class=\"column-2\">2 lb 4 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-26 even\">\n\t\t<td class=\"column-1\">Julie Doyon <\/td><td class=\"column-2\">2 lb 4 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-27 odd\">\n\t\t<td class=\"column-1\">\u00a0\u00a0Pierre Lirette<\/td><td class=\"column-2\">2 lb 4 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-28 even\">\n\t\t<td class=\"column-1\">St\u00e9phane Beaul\u00e9<\/td><td class=\"column-2\">2 lb 4 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-29 odd\">\n\t\t<td class=\"column-1\">Richard N\u00e9ron<\/td><td class=\"column-2\">2 lb 4 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 26<\/td>\n\t<\/tr>\n\t<tr class=\"row-30 even\">\n\t\t<td class=\"column-1\">Fran\u00e7ois M\u00e9nard<\/td><td class=\"column-2\">2 lb 5 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 20<\/td>\n\t<\/tr>\n\t<tr class=\"row-31 odd\">\n\t\t<td class=\"column-1\">Suzie Heppel<\/td><td class=\"column-2\">2 lb 5 oz<\/td><td class=\"column-3\">Charit\u00e9 2 <\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-32 even\">\n\t\t<td class=\"column-1\">Marc Andr\u00e9 Cormier<\/td><td class=\"column-2\">2 lb 5 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-33 odd\">\n\t\t<td class=\"column-1\">Richard Gagn\u00e9<\/td><td class=\"column-2\">2 lb 5 oz<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 28<\/td>\n\t<\/tr>\n\t<tr class=\"row-34 even\">\n\t\t<td class=\"column-1\">Johane Durand<\/td><td class=\"column-2\">2 lb 6 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 13<\/td>\n\t<\/tr>\n\t<tr class=\"row-35 odd\">\n\t\t<td class=\"column-1\">Danielle Lagace<\/td><td class=\"column-2\">2 lb 6 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 22<\/td>\n\t<\/tr>\n\t<tr class=\"row-36 even\">\n\t\t<td class=\"column-1\">Guillaume Huot<\/td><td class=\"column-2\">2 lb 6 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">july 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-37 odd\">\n\t\t<td class=\"column-1\">Lise Duquette<\/td><td class=\"column-2\">2 lb 6 oz<\/td><td class=\"column-3\">Foy<\/td><td class=\"column-4\">may 16<\/td>\n\t<\/tr>\n\t<tr class=\"row-38 even\">\n\t\t<td class=\"column-1\">Denis Turcotte<\/td><td class=\"column-2\">2 lb 7 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-39 odd\">\n\t\t<td class=\"column-1\">Jean-Fran\u00e7ois Asselin<\/td><td class=\"column-2\">2 lb 7 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-40 even\">\n\t\t<td class=\"column-1\">Marcel Frenette<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 27<\/td>\n\t<\/tr>\n\t<tr class=\"row-41 odd\">\n\t\t<td class=\"column-1\">Fran\u00e7ois Menard<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Charit\u00e9 2<\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-42 even\">\n\t\t<td class=\"column-1\">Martin Dickner<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Foi<\/td><td class=\"column-4\">june 25<\/td>\n\t<\/tr>\n\t<tr class=\"row-43 odd\">\n\t\t<td class=\"column-1\">Mathew Mc Laughlin<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Foi<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-44 even\">\n\t\t<td class=\"column-1\">Alexandre Tremblay<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Charit\u00e9 2<\/td><td class=\"column-4\">may 20<\/td>\n\t<\/tr>\n\t<tr class=\"row-45 odd\">\n\t\t<td class=\"column-1\">Raymond Renaud<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 15<\/td>\n\t<\/tr>\n\t<tr class=\"row-46 even\">\n\t\t<td class=\"column-1\">Guillaume Blais<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 21<\/td>\n\t<\/tr>\n\t<tr class=\"row-47 odd\">\n\t\t<td class=\"column-1\">Isabelle Imbeault<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-48 even\">\n\t\t<td class=\"column-1\">Eric Verrier<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Foy<\/td><td class=\"column-4\">may 15<\/td>\n\t<\/tr>\n\t<tr class=\"row-49 odd\">\n\t\t<td class=\"column-1\">Jean Masson<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-50 even\">\n\t\t<td class=\"column-1\">S\u00e9bastien Perron<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-51 odd\">\n\t\t<td class=\"column-1\">Mathew Mc Laughlin<\/td><td class=\"column-2\">2 lb 8 oz<\/td><td class=\"column-3\">Charit\u00e9 2<\/td><td class=\"column-4\">may 13<\/td>\n\t<\/tr>\n\t<tr class=\"row-52 even\">\n\t\t<td class=\"column-1\">Louise Vachon<\/td><td class=\"column-2\">2 lb 8 oz <\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 15<\/td>\n\t<\/tr>\n\t<tr class=\"row-53 odd\">\n\t\t<td class=\"column-1\">Pierre Lirette<\/td><td class=\"column-2\">2 lb 9 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-54 even\">\n\t\t<td class=\"column-1\">Michel Desrosiers<\/td><td class=\"column-2\">2 lb 9oz<\/td><td class=\"column-3\">Charit\u00e9 2<\/td><td class=\"column-4\">june 2<\/td>\n\t<\/tr>\n\t<tr class=\"row-55 odd\">\n\t\t<td class=\"column-1\">Jean Philippe Morency<\/td><td class=\"column-2\">2 lb 10 oz<\/td><td class=\"column-3\">Charit\u00e9 2<\/td><td class=\"column-4\">may 18<\/td>\n\t<\/tr>\n\t<tr class=\"row-56 even\">\n\t\t<td class=\"column-1\">Jacques Gaudreault<\/td><td class=\"column-2\">2 lb 10 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 8<\/td>\n\t<\/tr>\n\t<tr class=\"row-57 odd\">\n\t\t<td class=\"column-1\">Gabrielle Hudon<\/td><td class=\"column-2\">2 lb 10 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-58 even\">\n\t\t<td class=\"column-1\">Jean Philippe Morency<\/td><td class=\"column-2\">2 lb 11 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 18<\/td>\n\t<\/tr>\n\t<tr class=\"row-59 odd\">\n\t\t<td class=\"column-1\">lucille Langlois<\/td><td class=\"column-2\">2 lb 11 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 4<\/td>\n\t<\/tr>\n\t<tr class=\"row-60 even\">\n\t\t<td class=\"column-1\">Jean Fran\u00e7ois Asselin<\/td><td class=\"column-2\">2 lb 11 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">19 may<\/td>\n\t<\/tr>\n\t<tr class=\"row-61 odd\">\n\t\t<td class=\"column-1\">Luc Langevin<\/td><td class=\"column-2\">2 lb 11 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-62 even\">\n\t\t<td class=\"column-1\">H\u00e9l\u00e8ne Brunelle<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Foy<\/td><td class=\"column-4\">may 15<\/td>\n\t<\/tr>\n\t<tr class=\"row-63 odd\">\n\t\t<td class=\"column-1\">Luc Morissette<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-64 even\">\n\t\t<td class=\"column-1\">Richard Moreau<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 26<\/td>\n\t<\/tr>\n\t<tr class=\"row-65 odd\">\n\t\t<td class=\"column-1\">Fran\u00e7ois Rochette<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 4<\/td>\n\t<\/tr>\n\t<tr class=\"row-66 even\">\n\t\t<td class=\"column-1\">Denis Thibaud<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-67 odd\">\n\t\t<td class=\"column-1\">Fran\u00e7ois Ricard<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 22<\/td>\n\t<\/tr>\n\t<tr class=\"row-68 even\">\n\t\t<td class=\"column-1\">Pierre Drapeau<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 9<\/td>\n\t<\/tr>\n\t<tr class=\"row-69 odd\">\n\t\t<td class=\"column-1\">L\u00e9andre Dumont<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9 <\/td><td class=\"column-4\">june 1<\/td>\n\t<\/tr>\n\t<tr class=\"row-70 even\">\n\t\t<td class=\"column-1\">Lise Duquette<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Foi<\/td><td class=\"column-4\">16 may<\/td>\n\t<\/tr>\n\t<tr class=\"row-71 odd\">\n\t\t<td class=\"column-1\">Jean Pierre Gamache<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 15<\/td>\n\t<\/tr>\n\t<tr class=\"row-72 even\">\n\t\t<td class=\"column-1\">Marthe Poulin<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 24<\/td>\n\t<\/tr>\n\t<tr class=\"row-73 odd\">\n\t\t<td class=\"column-1\">Julie Doyon<\/td><td class=\"column-2\">2 lb 12 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">12 may<\/td>\n\t<\/tr>\n\t<tr class=\"row-74 even\">\n\t\t<td class=\"column-1\">Marc-Olivier Caron<\/td><td class=\"column-2\">2 lb 13 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 26<\/td>\n\t<\/tr>\n\t<tr class=\"row-75 odd\">\n\t\t<td class=\"column-1\">Jean Guglia<\/td><td class=\"column-2\">2 lb 13 oz<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 16<\/td>\n\t<\/tr>\n\t<tr class=\"row-76 even\">\n\t\t<td class=\"column-1\">Richard Cyr<\/td><td class=\"column-2\">2 lb 13 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-77 odd\">\n\t\t<td class=\"column-1\">Antoine Laroche<\/td><td class=\"column-2\">2 lb 13 oz<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 13<\/td>\n\t<\/tr>\n\t<tr class=\"row-78 even\">\n\t\t<td class=\"column-1\">Raymond Renaud<\/td><td class=\"column-2\">2 lb 14 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 14<\/td>\n\t<\/tr>\n\t<tr class=\"row-79 odd\">\n\t\t<td class=\"column-1\">Fr\u00e9d\u00e9ric Hisotte<\/td><td class=\"column-2\">2 lb 14 oz<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 16<\/td>\n\t<\/tr>\n\t<tr class=\"row-80 even\">\n\t\t<td class=\"column-1\">Jean-Philippe Asselin<\/td><td class=\"column-2\">2 lb 14 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-81 odd\">\n\t\t<td class=\"column-1\">Dominique Milot<\/td><td class=\"column-2\">2 lb 14 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">june 2<\/td>\n\t<\/tr>\n\t<tr class=\"row-82 even\">\n\t\t<td class=\"column-1\">Fernand Rioux <\/td><td class=\"column-2\">2 lb 14 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 18<\/td>\n\t<\/tr>\n\t<tr class=\"row-83 odd\">\n\t\t<td class=\"column-1\">Lise Dicaire<\/td><td class=\"column-2\">2 lb 15 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 31<\/td>\n\t<\/tr>\n\t<tr class=\"row-84 even\">\n\t\t<td class=\"column-1\">Ren\u00e9 Drouin<\/td><td class=\"column-2\">2lb<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">june 4<\/td>\n\t<\/tr>\n\t<tr class=\"row-85 odd\">\n\t\t<td class=\"column-1\">Carol Lapointe<\/td><td class=\"column-2\">2lb 3 oz<\/td><td class=\"column-3\">Vert<\/td><td class=\"column-4\">may 16<\/td>\n\t<\/tr>\n\t<tr class=\"row-86 even\">\n\t\t<td class=\"column-1\">Ren\u00e9 Servais<\/td><td class=\"column-2\">2lb 4 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-87 odd\">\n\t\t<td class=\"column-1\">Serge Gagn\u00e9<\/td><td class=\"column-2\">2lb 5 oz<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 16<\/td>\n\t<\/tr>\n\t<tr class=\"row-88 even\">\n\t\t<td class=\"column-1\">Paul Dufresne<\/td><td class=\"column-2\">2lb 9 oz<\/td><td class=\"column-3\">Light<\/td><td class=\"column-4\">may 16<\/td>\n\t<\/tr>\n\t<tr class=\"row-89 odd\">\n\t\t<td class=\"column-1\">Mathew Mc Laughlin<\/td><td class=\"column-2\">2lb 10 oz<\/td><td class=\"column-3\">Foi<\/td><td class=\"column-4\">may 12 <\/td>\n\t<\/tr>\n\t<tr class=\"row-90 even\">\n\t\t<td class=\"column-1\">Richard Loyer<\/td><td class=\"column-2\">2lb 10 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 19<\/td>\n\t<\/tr>\n\t<tr class=\"row-91 odd\">\n\t\t<td class=\"column-1\">Chantal Berub\u00e9<\/td><td class=\"column-2\">2lb 10 oz<\/td><td class=\"column-3\">Charit\u00e9 1<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-92 even\">\n\t\t<td class=\"column-1\">Michel Fontaine<\/td><td class=\"column-2\">2lb 11 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-93 odd\">\n\t\t<td class=\"column-1\">Michel Fontaine<\/td><td class=\"column-2\">2lb 12 oz<\/td><td class=\"column-3\">Charit\u00e9<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n\t<tr class=\"row-94 even\">\n\t\t<td class=\"column-1\">Jean Masson<\/td><td class=\"column-2\">2lb 12 oz<\/td><td class=\"column-3\">Petit Esp\u00e9rance<\/td><td class=\"column-4\">may 12<\/td>\n\t<\/tr>\n\t<tr class=\"row-95 odd\">\n\t\t<td class=\"column-1\">Louise Desrosiers<\/td><td class=\"column-2\">2lb 12 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">may 11<\/td>\n\t<\/tr>\n\t<tr class=\"row-96 even\">\n\t\t<td class=\"column-1\">Line Laprise<\/td><td class=\"column-2\">2lb 13 oz<\/td><td class=\"column-3\">Esp\u00e9rance<\/td><td class=\"column-4\">june 2<\/td>\n\t<\/tr>\n\t<tr class=\"row-97 odd\">\n\t\t<td class=\"column-1\">Claudie Bouillon<\/td><td class=\"column-2\">2lb 14 oz<\/td><td class=\"column-3\">Foy<\/td><td class=\"column-4\">may 17<\/td>\n\t<\/tr>\n<\/tbody>\n<\/table>\n<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>4 lbs and over 3 lbs and over 2 lbs and over<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":67,"menu_order":25,"comment_status":"open","ping_status":"closed","template":"page-club2livres.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3244","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2012 - Seigneurie du Triton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2012 - Seigneurie du Triton\" \/>\n<meta property=\"og:description\" content=\"4 lbs and over 3 lbs and over 2 lbs and over\" \/>\n<meta property=\"og:url\" content=\"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Seigneurie du Triton\" \/>\n<meta property=\"article:modified_time\" content=\"2014-09-11T19:50:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/2-pounds-club\\\/years\\\/2012-en\\\/\",\"url\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/2-pounds-club\\\/years\\\/2012-en\\\/\",\"name\":\"2012 - Seigneurie du Triton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/#website\"},\"datePublished\":\"2014-03-19T19:50:17+00:00\",\"dateModified\":\"2014-09-11T19:50:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/2-pounds-club\\\/years\\\/2012-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/2-pounds-club\\\/years\\\/2012-en\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/2-pounds-club\\\/years\\\/2012-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Informations\",\"item\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2 pounds club\",\"item\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/2-pounds-club\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Years\",\"item\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/informations\\\/2-pounds-club\\\/years\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"2012\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/\",\"name\":\"Seigneurie du Triton\",\"description\":\"La Seigneurie du Triton: une prestigieuse pourvoirie au Canada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/seigneuriedutriton.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2012 - Seigneurie du Triton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/","og_locale":"en_US","og_type":"article","og_title":"2012 - Seigneurie du Triton","og_description":"4 lbs and over 3 lbs and over 2 lbs and over","og_url":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/","og_site_name":"Seigneurie du Triton","article_modified_time":"2014-09-11T19:50:25+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/","url":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/","name":"2012 - Seigneurie du Triton","isPartOf":{"@id":"https:\/\/seigneuriedutriton.com\/en\/#website"},"datePublished":"2014-03-19T19:50:17+00:00","dateModified":"2014-09-11T19:50:25+00:00","breadcrumb":{"@id":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/2012-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/seigneuriedutriton.com\/en\/"},{"@type":"ListItem","position":2,"name":"Informations","item":"https:\/\/seigneuriedutriton.com\/en\/informations\/"},{"@type":"ListItem","position":3,"name":"2 pounds club","item":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/"},{"@type":"ListItem","position":4,"name":"Years","item":"https:\/\/seigneuriedutriton.com\/en\/informations\/2-pounds-club\/years\/"},{"@type":"ListItem","position":5,"name":"2012"}]},{"@type":"WebSite","@id":"https:\/\/seigneuriedutriton.com\/en\/#website","url":"https:\/\/seigneuriedutriton.com\/en\/","name":"Seigneurie du Triton","description":"La Seigneurie du Triton: une prestigieuse pourvoirie au Canada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/seigneuriedutriton.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/pages\/3244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/comments?post=3244"}],"version-history":[{"count":0,"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/pages\/3244\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/pages\/67"}],"wp:attachment":[{"href":"https:\/\/seigneuriedutriton.com\/en\/wp-json\/wp\/v2\/media?parent=3244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}